{"id":42626,"date":"2025-01-21T12:12:30","date_gmt":"2025-01-21T10:12:30","guid":{"rendered":"https:\/\/www.buzon-world.com\/?page_id=42626"},"modified":"2026-05-05T10:49:47","modified_gmt":"2026-05-05T08:49:47","slug":"e-brs-stop-round","status":"publish","type":"page","link":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/","title":{"rendered":"E-BRS-STOP-ROUND"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_4fd89a8b height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_raw_html]JTVCd3BzZW9fYnJlYWRjcnVtYiU1RCUwQQ==[\/vc_raw_html]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 vc_col-lg-5 vc_col-md-6 vc_col-xs-12 wpb_column vc_column_container\"><div class=\"vc_column-inner type_sticky\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_scaledown nav_thumbs count_1\" style=\"--thumbs-width:4rem;--thumbs-gap:4px;\"><div class=\"w-slider-h\" aria-hidden=\"true\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"1024\" data-rsBigImg=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png\" href=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-1024x1024.png\"><span data-alt=\"\"><\/span><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-150x150.png\" class=\"rsTmb\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-400x400.png 400w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-600x600.png 600w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png 2000w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02-1024x1024.png\" width=\"1024\" height=\"1024\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:true,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;move&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;fullscreen&quot;:{&quot;enabled&quot;:true},&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:1024}'><\/div><\/div><time class=\"w-post-elm post_date pagedate entry-date published\" datetime=\"2025-01-21T12:12:30+02:00\" itemprop=\"datePublished\">2025-01-21<\/time><div class=\"w-image us_custom_bad8ca8b newpage has_height align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1 vc_hidden-md vc_hidden-sm vc_hidden-xs wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"vc_col-sm-12 vc_col-lg-6 vc_col-md-6 vc_col-xs-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column longline\"><div class=\"wpb_wrapper\"><h1>Cale d\u2019extr\u00e9mit\u00e9<br \/>\nangulaire<\/h1>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_5355a658\"><div class=\"wpb_wrapper\"><p><strong>E-BRS-STOP-ROUND<\/strong> (24 3385)<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>La cale d\u2019extr\u00e9mit\u00e9 pour lambourde (<strong>E-BRS-STOP<\/strong>) se glisse dans la lambourde et permet de maintenir les dalles p\u00e9riph\u00e9riques en position.<\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><span class=\"w-text bwavantages\"><span class=\"w-text-h\"><span class=\"w-text-value\">Avantages et utilisations<\/span><\/span><\/span><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"w-iconbox us_custom_0f8f44b7 iconpos_left style_default color_primary align_left no_title\"><div class=\"w-iconbox-icon\" style=\"font-size:5rem;\"><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><div class=\"w-iconbox-meta\">\n<div class=\"w-iconbox-text\">\n<p>Garantit un espace constant entre le mur et les dalles pour favoriser le bon \u00e9coulement p\u00e9riph\u00e9rique de l\u2019eau.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_0f8f44b7 iconpos_left style_default color_primary align_left no_title\"><div class=\"w-iconbox-icon\" style=\"font-size:5rem;\"><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p>\u00c9vite que les ar\u00eates des dalles d\u00e9t\u00e9riorent les murs et les remont\u00e9es d\u2019\u00e9tanch\u00e9it\u00e9.<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_0f8f44b7 iconpos_left style_default color_primary align_left no_title\"><div class=\"w-iconbox-icon\" style=\"font-size:5rem;\"><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p>Se fixe \u00e0 l\u2019aide de vis.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_middle wrap align_none\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-iconbox us_custom_0f8f44b7 buzonbox iconpos_left style_default color_primary align_left no_text icontype_img\"><a href=\"#downloads\" class=\"w-iconbox-link\" aria-label=\"T\u00e9l\u00e9chargements\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><?xml version=\"1.0\" encoding=\"utf-8\"?>\n<!-- Generator: Adobe Illustrator 26.3.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n<svg version=\"1.1\" id=\"Group_2361\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 57.6 72\" style=\"enable-background:new 0 0 57.6 72;\" xml:space=\"preserve\">\n<style type=\"text\/css\">\n\t.st0{fill:#FFFFFF;}\n<\/style>\n<path class=\"st0\" d=\"M57.6,15.6C57.6,15.6,57.6,15.5,57.6,15.6c0-0.1-0.1-0.3-0.1-0.4c0,0,0-0.1,0-0.1c-0.1-0.1-0.1-0.2-0.2-0.3\n\tL42.8,0.4c-0.1-0.1-0.2-0.2-0.3-0.2c0,0-0.1,0-0.1,0C42.3,0,42.2,0,42.1,0c0,0,0,0,0,0c-0.1,0-0.2,0-0.3,0H7.2c-4,0-7.3,3.3-7.3,7.3\n\tv57.6c0,4,3.3,7.3,7.3,7.3h43.2c4,0,7.3-3.3,7.3-7.3v-49C57.7,15.7,57.6,15.6,57.6,15.6z\"\/>\n<g id=\"Path_2390\">\n\t<path d=\"M50.4,72.1H7.2c-4,0-7.3-3.3-7.3-7.3V7.2c0-4,3.3-7.3,7.3-7.3h34.6c0.8,0,1.5,0.7,1.5,1.5v12.9h12.9c0.8,0,1.5,0.7,1.5,1.5\n\t\tv49C57.7,68.8,54.4,72.1,50.4,72.1z M7.2,2.9c-2.3,0-4.3,1.9-4.3,4.3v57.6c0,2.3,1.9,4.3,4.3,4.3h43.2c2.3,0,4.3-1.9,4.3-4.3V17.3\n\t\tH41.8c-0.8,0-1.5-0.7-1.5-1.5V2.9H7.2z\"\/>\n<\/g>\n<g id=\"Path_2391\">\n\t<path d=\"M56.2,17.3H41.8c-0.8,0-1.5-0.7-1.5-1.5V1.4c0-0.6,0.4-1.2,0.9-1.4s1.2-0.1,1.6,0.3l14.4,14.4c0.4,0.4,0.6,1.1,0.3,1.6\n\t\tS56.8,17.3,56.2,17.3z M43.3,14.3h9.3l-9.3-9.3V14.3z\"\/>\n<\/g>\n<g id=\"Rectangle_295\">\n\t<path d=\"M46.1,57.1H11.5c-0.8,0-1.5-0.7-1.5-1.5v-31c0-0.8,0.7-1.5,1.5-1.5h34.6c0.8,0,1.5,0.7,1.5,1.5v31\n\t\tC47.6,56.4,46.9,57.1,46.1,57.1z M13,54.1h31.6v-28H13V54.1z\"\/>\n<\/g>\n<g id=\"Path_2392\">\n\t<path d=\"M35.9,57.1H11.5c-0.6,0-1.2-0.4-1.4-0.9c-0.2-0.6-0.1-1.2,0.3-1.6l12.2-12.2c0.6-0.6,1.6-0.6,2.1,0L37,54.5\n\t\tc0.4,0.4,0.6,1.1,0.3,1.6S36.5,57.1,35.9,57.1z M15.1,54.1h17.2l-8.6-8.6L15.1,54.1z\"\/>\n<\/g>\n<g id=\"Path_2393\">\n\t<path d=\"M46.1,57.1H35.9c-0.4,0-0.8-0.2-1.1-0.4l-5.1-5.1c-0.6-0.6-0.6-1.5,0-2.1l5.1-5.1c0.6-0.6,1.5-0.6,2.1,0l10.2,10.2\n\t\tc0.4,0.4,0.6,1.1,0.3,1.6S46.7,57.1,46.1,57.1z M36.5,54.1h5.9l-6.5-6.5l-3,3L36.5,54.1z\"\/>\n<\/g>\n<g id=\"Path_2394\">\n\t<path d=\"M29.8,40.6c-1.5,0-2.9-0.6-3.9-1.6c-1.1-1.1-1.6-2.4-1.6-3.9c0-3.1,2.5-5.6,5.6-5.6c3.1,0,5.6,2.5,5.6,5.6c0,0,0,0,0,0\n\t\tc0,1.5-0.6,2.9-1.6,3.9C32.7,40,31.3,40.6,29.8,40.6C29.8,40.6,29.8,40.6,29.8,40.6z M29.8,32.5c-1.4,0-2.6,1.2-2.6,2.6\n\t\tc0,0.7,0.3,1.3,0.8,1.8c0.5,0.5,1.1,0.8,1.8,0.8c0,0,0,0,0,0c0.7,0,1.3-0.3,1.8-0.8c0.5-0.5,0.8-1.1,0.8-1.8\n\t\tC32.4,33.6,31.2,32.5,29.8,32.5z\"\/>\n<\/g>\n<\/svg>\n<\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"#downloads\" class=\"w-iconbox-link\" aria-label=\"T\u00e9l\u00e9chargements\">T\u00e9l\u00e9chargements<\/a><\/p><\/div><\/div><div class=\"w-iconbox us_custom_0f8f44b7 buzonbox iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"#application\" class=\"w-iconbox-link\" aria-label=\"Application\"><div class=\"w-iconbox-icon\" style=\"font-size:4rem;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"73\" height=\"73\" viewBox=\"0 0 73 73\"><defs><style>.a,.c{fill:#f7f7f7;}.a{stroke:#000;stroke-width:3px;}.b{clip-path:url(#a);}<\/style><clipPath id=\"a\"><rect class=\"a\" width=\"73\" height=\"73\"\/><\/clipPath><\/defs><g transform=\"translate(0 0)\"><g class=\"b\" transform=\"translate(0 0)\"><path class=\"c\" d=\"M60.432,11.2a34.814,34.814,0,1,1-49.235,0A34.815,34.815,0,0,1,60.432,11.2Z\" transform=\"translate(0.685 0.686)\"\/><path d=\"M35.815-.5A36.205,36.205,0,1,1,22.15,2.16,36.193,36.193,0,0,1,35.815-.5Zm0,69.629A33.2,33.2,0,1,0,23.278,66.69,33.2,33.2,0,0,0,35.815,69.129Z\" transform=\"translate(0.685 0.686)\"\/><path class=\"c\" d=\"M41.846,23.874H34.036V16.063a5.081,5.081,0,0,0-10.162,0v7.811H16.063a5.08,5.08,0,0,0,0,10.16h7.811v7.812A5.056,5.056,0,0,0,28.93,46.9h.049a5.057,5.057,0,0,0,5.056-5.056V34.034h7.811a5.08,5.08,0,0,0,0-10.16Z\" transform=\"translate(7.545 7.545)\"\/><path d=\"M28.93,9.507a6.588,6.588,0,0,1,6.605,6.556v6.311h6.311a6.58,6.58,0,0,1,0,13.16H35.536v6.312A6.564,6.564,0,0,1,28.979,48.4H28.93a6.564,6.564,0,0,1-6.556-6.556V35.534H16.063a6.58,6.58,0,0,1,0-13.16h6.311V16.063A6.564,6.564,0,0,1,28.93,9.507ZM41.846,32.534a3.5,3.5,0,0,0,2.508-1.058A3.6,3.6,0,0,0,45.4,28.93a3.56,3.56,0,0,0-3.556-3.556H32.536V16.063a3.5,3.5,0,0,0-1.059-2.508,3.606,3.606,0,0,0-2.546-1.049,3.56,3.56,0,0,0-3.556,3.556v9.311H16.063a3.5,3.5,0,0,0-2.508,1.058,3.6,3.6,0,0,0-1.048,2.545,3.56,3.56,0,0,0,3.556,3.556h9.311v9.312A3.56,3.56,0,0,0,28.93,45.4h.049a3.56,3.56,0,0,0,3.556-3.556V32.534Z\" transform=\"translate(7.545 7.545)\"\/><\/g><\/g><\/svg><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"#application\" class=\"w-iconbox-link\" aria-label=\"Application\">Application<\/a><\/p><\/div><\/div><div class=\"w-iconbox us_custom_0f8f44b7 buzonbox iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"#accessories\" class=\"w-iconbox-link\" aria-label=\"Accessoires\"><div class=\"w-iconbox-icon\" style=\"font-size:4rem;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"73\" height=\"73\" viewBox=\"0 0 73 73\"><defs><style>.a,.c{fill:#f7f7f7;}.a{stroke:#000;stroke-width:3px;}.b{clip-path:url(#a);}<\/style><clipPath id=\"a\"><rect class=\"a\" width=\"73\" height=\"73\"\/><\/clipPath><\/defs><g transform=\"translate(0 0)\"><g class=\"b\" transform=\"translate(0 0)\"><path class=\"c\" d=\"M60.432,11.2a34.814,34.814,0,1,1-49.235,0A34.815,34.815,0,0,1,60.432,11.2Z\" transform=\"translate(0.685 0.686)\"\/><path d=\"M35.815-.5A36.205,36.205,0,1,1,22.15,2.16,36.193,36.193,0,0,1,35.815-.5Zm0,69.629A33.2,33.2,0,1,0,23.278,66.69,33.2,33.2,0,0,0,35.815,69.129Z\" transform=\"translate(0.685 0.686)\"\/><path class=\"c\" d=\"M41.846,23.874H34.036V16.063a5.081,5.081,0,0,0-10.162,0v7.811H16.063a5.08,5.08,0,0,0,0,10.16h7.811v7.812A5.056,5.056,0,0,0,28.93,46.9h.049a5.057,5.057,0,0,0,5.056-5.056V34.034h7.811a5.08,5.08,0,0,0,0-10.16Z\" transform=\"translate(7.545 7.545)\"\/><path d=\"M28.93,9.507a6.588,6.588,0,0,1,6.605,6.556v6.311h6.311a6.58,6.58,0,0,1,0,13.16H35.536v6.312A6.564,6.564,0,0,1,28.979,48.4H28.93a6.564,6.564,0,0,1-6.556-6.556V35.534H16.063a6.58,6.58,0,0,1,0-13.16h6.311V16.063A6.564,6.564,0,0,1,28.93,9.507ZM41.846,32.534a3.5,3.5,0,0,0,2.508-1.058A3.6,3.6,0,0,0,45.4,28.93a3.56,3.56,0,0,0-3.556-3.556H32.536V16.063a3.5,3.5,0,0,0-1.059-2.508,3.606,3.606,0,0,0-2.546-1.049,3.56,3.56,0,0,0-3.556,3.556v9.311H16.063a3.5,3.5,0,0,0-2.508,1.058,3.6,3.6,0,0,0-1.048,2.545,3.56,3.56,0,0,0,3.556,3.556h9.311v9.312A3.56,3.56,0,0,0,28.93,45.4h.049a3.56,3.56,0,0,0,3.556-3.556V32.534Z\" transform=\"translate(7.545 7.545)\"\/><\/g><\/g><\/svg><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"#accessories\" class=\"w-iconbox-link\" aria-label=\"Accessoires\">Accessoires<\/a><\/p><\/div><\/div><div class=\"w-iconbox us_custom_0f8f44b7 buzonbox iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"#videos\" class=\"w-iconbox-link\" aria-label=\"Vid\u00e9os\"><div class=\"w-iconbox-icon\" style=\"font-size:4rem;\"><?xml version=\"1.0\" encoding=\"UTF-8\"?><svg id=\"Layer_2\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 29.64 29.65\"><defs><style>.cls-1{fill:#fff;}<\/style><\/defs><g id=\"Layer_1-2\"><g><g id=\"Group_2354\"><g id=\"Path_2385\"><path class=\"cls-1\" d=\"M24.86,4.78c5.55,5.55,5.55,14.54,0,20.09-5.55,5.55-14.54,5.55-20.09,0C-.77,19.32-.77,10.33,4.77,4.78,10.32-.77,19.31-.77,24.86,4.78Z\"\/><path d=\"M14.82,29.65c-3.96,0-7.68-1.54-10.48-4.34C-1.44,19.53-1.44,10.12,4.33,4.34,7.13,1.54,10.86,0,14.82,0s7.68,1.54,10.48,4.34h0c2.8,2.8,4.34,6.52,4.34,10.48s-1.54,7.68-4.34,10.48c-2.8,2.8-6.52,4.34-10.48,4.34ZM14.82,1.24c-3.63,0-7.04,1.41-9.6,3.98C-.08,10.51-.08,19.13,5.21,24.43c2.57,2.57,5.98,3.98,9.6,3.98s7.04-1.41,9.6-3.98,3.98-5.98,3.98-9.6-1.41-7.04-3.98-9.6h0c-2.57-2.57-5.98-3.98-9.6-3.98Z\"\/><\/g><\/g><g><path class=\"cls-1\" d=\"M11.65,14.82v-3.9c0-.62,.67-1.01,1.21-.7l3.37,1.95,3.37,1.95c.54,.31,.54,1.09,0,1.4l-3.37,1.95-3.37,1.95c-.54,.31-1.21-.08-1.21-.7v-3.9Z\"\/><path d=\"M12.46,20.15c-.25,0-.49-.06-.71-.19-.45-.26-.71-.72-.71-1.24v-7.79c0-.52,.27-.98,.71-1.24,.45-.26,.98-.26,1.43,0l6.75,3.9c.45,.26,.71,.72,.71,1.24s-.27,.98-.71,1.24l-6.75,3.9c-.22,.13-.47,.19-.71,.19Zm0-9.41s-.07,.01-.09,.03c-.04,.02-.09,.07-.09,.16v7.79c0,.09,.06,.14,.09,.16,.04,.02,.11,.05,.19,0l6.75-3.9c.08-.05,.09-.12,.09-.16s-.01-.11-.09-.16l-6.75-3.9s-.06-.03-.09-.03Z\"\/><\/g><\/g><\/g><\/svg><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"#videos\" class=\"w-iconbox-link\" aria-label=\"Vid\u00e9os\">Vid\u00e9os<\/a><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_5\" title=\"Contact\" href=\"https:\/\/www.buzon-world.com\/fr\/contact\/\"><span class=\"w-btn-label\">Contactez un expert<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\" id=\"downloads\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column longline\"><div class=\"wpb_wrapper\"><h2>T\u00e9l\u00e9chargements<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_left style_default color_primary align_left no_text icontype_img\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/Installation-Guide_E-BRS_accessoires_FR.pdf\" class=\"w-iconbox-link\" aria-label=\"Guide d&rsquo;installation E-BRS\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Technicalsheet.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Technicalsheet.png 240w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Technicalsheet-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Technicalsheet-70x70.png 70w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/Installation-Guide_E-BRS_accessoires_FR.pdf\" class=\"w-iconbox-link\" aria-label=\"Guide d&rsquo;installation E-BRS\">Guide d&rsquo;installation E-BRS<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_left style_default color_primary align_left no_text icontype_img\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/TDS_E-BRS-STOP-ROUND-1.pdf\" class=\"w-iconbox-link\" aria-label=\"Fiche Technique E-BRS-STOP-ROUND\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/brochure.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/brochure.png 240w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/brochure-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/brochure-70x70.png 70w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/TDS_E-BRS-STOP-ROUND-1.pdf\" class=\"w-iconbox-link\" aria-label=\"Fiche Technique E-BRS-STOP-ROUND\">Fiche Technique E-BRS-STOP-ROUND<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\" id=\"videos\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column longline\"><div class=\"wpb_wrapper\"><h2>Videos<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-video align_center ratio_16x9 has_iframe\"><div class=\"w-video-h\"><iframe title=\"Youtube video player\" src=\"\/\/www.youtube.com\/embed\/odpE8gUrGSg?autoplay=0&controls=1&origin=https:\/\/www.buzon-world.com\/fr\/&loop=0&mute=0\" allowfullscreen=\"1\" loading=\"lazy\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\" id=\"accessories\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column longline\"><div class=\"wpb_wrapper\"><h2>ACCESSOIRES DE LA GAMME E-BRS<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-grid us_grid shadowgrid with_filters type_grid layout_581 cols_3 pagination_ajax preload_style_spinner\" id=\"us_grid_1\" style=\"--columns:3;--gap:1rem;\"><style>@media (max-width:1024px){#us_grid_1{--columns:2!important}}@media (max-width:767px){#us_grid_1{--columns:1!important}}.layout_581 .w-grid-item-h{}.layout_581 .usg_post_title_1{margin-top:20px!important;margin-bottom:20px!important}.layout_581 .usg_post_custom_field_1{padding-bottom:40px!important}<\/style><div class=\"g-filters style_1 align_left\"><button class=\"g-filters-item active\" data-taxonomy=\"terrasse-en-dalles-sur-lambourdes\" data-amount=\"12\"><span>Terrasse en dalles sur lambourdes<\/span><span class=\"g-filters-item-amount\">12<\/span><\/button><\/div><div class=\"w-grid-list\" data-filter_taxonomy_name=\"accesories_category\" data-filter_default_taxonomies=\"terrasse-en-dalles-sur-lambourdes\">\t<article class=\"w-grid-item size_1x1 post-41682 page type-page status-publish has-post-thumbnail hentry accesories_category-serie-dph accesories_category-accessoires-de-base accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-accessoires-de-base-2 accesories_category-serie-pb\" data-id=\"41682\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/e-brs-system\/e-brs\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder.jpg\" class=\"g-placeholder\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder.jpg 1000w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-70x70.jpg 70w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/e-brs-system\/e-brs\/\" aria-label=\"E-BRS\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/E-BRS-41-B_2-1024x1024.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/e-brs-system\/e-brs\/\">E-BRS<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/e-brs-system\/e-brs\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2023-12-08T15:05:43+02:00\">2023-12-08<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10325 page type-page status-publish has-post-thumbnail hentry accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-de-base accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite accesories_category-accessoires-de-base-2 accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoires-de-base accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10325\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-1\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT-1024x1024.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT-70x70.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-1\/\" aria-label=\"U-FIXING-PLATE-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-1-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-1\/\">U-FIXING-PLATE-1<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-1\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-25T15:03:30+02:00\">2022-07-25<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10252 page type-page status-publish has-post-thumbnail hentry accesories_category-serie-dph accesories_category-terrasse-en-dalles-sur-plots-2 accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-bois-ou-composite accesories_category-accessoires-complementaires-2 accesories_category_type-serie-dph accessories_categories_subtype-accessoires-complementaires accessories_categories_applica-terrasse-en-dalles-sur-plots accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10252\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-dph\/dph-ph5\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"822\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/DPH-PH5-PACKSHOT-1024x822.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/DPH-PH5-PACKSHOT-1024x822.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/DPH-PH5-PACKSHOT-300x241.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/DPH-PH5-PACKSHOT-70x56.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/DPH-PH5-PACKSHOT.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-dph\/dph-ph5\/\" aria-label=\"DPH-PH5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"822\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/DPH-PH5-PACKSHOT-1024x822.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-dph\/dph-ph5\/\">DPH-PH5<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-dph\/dph-ph5\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-25T14:50:28+02:00\">2022-07-25<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10324 page type-page status-publish has-post-thumbnail hentry accesories_category-accessoires-de-base accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite-2 accesories_category-terrasse-en-bois-ou-composite accesories_category-accessoires-de-base-2 accesories_category-serie-pb accesories_category-serie-dph accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoires-de-base accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10324\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-5\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT-1024x1024.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT-70x70.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-5\/\" aria-label=\"U-FIXING-PLATE-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-FIXING-PLATE-5-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-5\/\">U-FIXING-PLATE-5<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-fixing-plate-5\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-25T15:03:30+02:00\">2022-07-25<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10275 page type-page status-publish has-post-thumbnail hentry accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite-2 accesories_category-terrasse-en-bois-ou-composite accesories_category-accessoires-complementaires-2 accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-complementaires accesories_category-terrasse-en-dalles-sur-plots accesories_category-terrasse-en-dalles-sur-plots-2 accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoires-complementaires accessories_categories_applica-terrasse-en-bois-ou-composite accessories_categories_applica-terrasse-en-dalles-sur-plots accessories_categories_applica-terrasse-en-dalles-sur-lambourdes\" data-id=\"10275\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"346\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PH5-PB-MOCK-UP-04-1024x346.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PH5-PB-MOCK-UP-04-1024x346.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PH5-PB-MOCK-UP-04-300x101.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PH5-PB-MOCK-UP-04-70x24.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PH5-PB-MOCK-UP-04.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5\/\" aria-label=\"U-PH5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PH5-PACKSHOT-01-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5\/\">U-PH5<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-25T14:32:24+02:00\">2022-07-25<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-42053 page type-page status-publish has-post-thumbnail hentry accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-de-base accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-accessoires-de-base-2\" data-id=\"42053\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-wall\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder.jpg\" class=\"g-placeholder\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder.jpg 1000w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-70x70.jpg 70w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-wall\/\" aria-label=\"E-BRS-WALL\"><div class=\"w-post-slider-trigger\" style=\"width:50%; left:0%;\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/E-BRS-WALL-PACKSHOT-02-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" \/><div class=\"w-post-slider-trigger\" style=\"width:50%; left:50%;\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/E-BRS-WALL-MOCKUP-02-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-wall\/\">E-BRS-WALL<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-wall\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2025-01-21T12:12:49+02:00\">2025-01-21<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10329 page type-page status-publish has-post-thumbnail hentry accesories_category-accessoires-de-base-2 accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-de-base accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite-2 accesories_category-terrasse-en-bois-ou-composite sizes-2mm-fr sizes-3mm-fr sizes-4-5mm-fr accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoires-de-base accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10329\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-tabs\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-BRS-TABS-MOCK-UP-03-1024x682.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-BRS-TABS-MOCK-UP-03-1024x682.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-BRS-TABS-MOCK-UP-03-300x200.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-BRS-TABS-MOCK-UP-03-70x47.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-BRS-TABS-MOCK-UP-03.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-tabs\/\" aria-label=\"U-BRS-TABS\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-BRS-TABS-2MM-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-tabs\/\">U-BRS-TABS<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-tabs\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-05T15:50:11+02:00\">2022-07-05<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10276 page type-page status-publish has-post-thumbnail hentry accesories_category-accessoires-complementaires-2 accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-complementaires accesories_category-terrasse-en-dalles-sur-plots accesories_category-terrasse-en-dalles-sur-plots-2 accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite-2 accesories_category-terrasse-en-bois-ou-composite accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoires-complementaires accessories_categories_applica-terrasse-en-dalles-sur-plots accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10276\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5-key-foot\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-PH5-KEY-FOOT-PB-ON-PEDESTAL-03-1024x684.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-PH5-KEY-FOOT-PB-ON-PEDESTAL-03-1024x684.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-PH5-KEY-FOOT-PB-ON-PEDESTAL-03-300x200.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-PH5-KEY-FOOT-PB-ON-PEDESTAL-03-70x47.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-PH5-KEY-FOOT-PB-ON-PEDESTAL-03.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5-key-foot\/\" aria-label=\"U-PH5-KEY-FOOT\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-PH5-KEY-FOOT-PACKSHOT_1-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5-key-foot\/\">U-PH5-KEY-FOOT<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-ph5-key-foot\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-25T14:32:24+02:00\">2022-07-25<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-42669 page type-page status-publish has-post-thumbnail hentry accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-de-base accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-accessoires-de-base-2 plot_serie-serie-pb plot_serie-serie-dph accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_applica-terrasse-en-dalles-sur-lambourdes\" data-id=\"42669\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-stop\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"802\" height=\"802\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/U-BRS-STOP-PACKSHOT-02.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/U-BRS-STOP-PACKSHOT-02.png 802w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/U-BRS-STOP-PACKSHOT-02-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/U-BRS-STOP-PACKSHOT-02-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/U-BRS-STOP-PACKSHOT-02-70x70.png 70w\" sizes=\"auto, (max-width: 802px) 100vw, 802px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-stop\/\" aria-label=\"U-BRS-STOP\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"870\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/11\/U-BRS-STOP-PACKSHOT-04.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-stop\/\">U-BRS-STOP<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/u-brs-stop\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2024-12-18T16:57:55+02:00\">2024-12-18<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10317 page type-page status-publish has-post-thumbnail hentry accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-accessoires-de-fixation-2 accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-de-fixation accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoireks-de-fixation accessories_categories_applica-terrasse-en-dalles-sur-lambourdes\" data-id=\"10317\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-brs-vis\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder.jpg\" class=\"g-placeholder\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder.jpg 1000w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/01\/image-placeholder-70x70.jpg 70w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-brs-vis\/\" aria-label=\"U-BRS-VIS\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2023\/12\/U-BRS-VIS-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-brs-vis\/\">U-BRS-VIS<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-brs-vis\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-10-27T16:20:51+02:00\">2022-10-27<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10269 page type-page status-publish has-post-thumbnail hentry accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-complementaires accesories_category-terrasse-en-dalles-sur-plots accesories_category-terrasse-en-dalles-sur-plots-2 accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite-2 accesories_category-terrasse-en-bois-ou-composite accesories_category-accessoires-complementaires-2 accesories_category_type-serie-dph accesories_category_type-serie-pb accessories_categories_subtype-accessoires-complementaires accessories_categories_applica-terrasse-en-dalles-sur-plots accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10269\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-kit-sl-80\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01-1024x1024.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01-70x70.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-kit-sl-80\/\" aria-label=\"U-KIT-SL-80\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-KIT-SL-80-PACKSHOT-01-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-kit-sl-80\/\">U-KIT-SL-80<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-kit-sl-80\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-25T14:33:31+02:00\">2022-07-25<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-10259 page type-page status-publish has-post-thumbnail hentry accesories_category-accessoires-complementaires-2 accesories_category-serie-pb accesories_category-serie-dph accesories_category-accessoires-complementaires accesories_category-matelas-et-ecarteurs-de-dalles accesories_category-terrasse-en-dalles-sur-plots accesories_category-terrasse-en-dalles-sur-plots-2 accesories_category-terrasse-en-dalles-sur-lambourdes accesories_category-terrasse-en-dalles-sur-lambourdes-2 accesories_category-terrasse-en-bois-ou-composite-2 accesories_category-terrasse-en-bois-ou-composite plot_serie-matelas-et-ecarteurs-de-dalles accesories_category_type-matelas-et-ecarteurs-de-dalles accesories_category_type-serie-pb accesories_category_type-serie-dph accessories_categories_subtype-accessoires-complementaires accessories_categories_applica-terrasse-en-dalles-sur-plots accessories_categories_applica-terrasse-en-dalles-sur-lambourdes accessories_categories_applica-terrasse-en-bois-ou-composite\" data-id=\"10259\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-hwrapper usg_hwrapper_1 flex4060 align_none valign_middle\" style=\"--hwrapper-gap:2rem\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_2 hoverimage type_image color_link_inherit has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-pad\/\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-PB-ON-PEDESTAL-01-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-PB-ON-PEDESTAL-01-1024x1024.jpg 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-PB-ON-PEDESTAL-01-300x300.jpg 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-PB-ON-PEDESTAL-01-150x150.jpg 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-PB-ON-PEDESTAL-01-70x70.jpg 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-PB-ON-PEDESTAL-01.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-pad\/\" aria-label=\"U-PAD\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/08\/U-PAD-10MM-200-PACKSHOT-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><h3 class=\"w-post-elm post_title usg_post_title_1 shortline entry-title color_link_inherit\"><a href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-pad\/\">U-PAD<\/a><\/h3><\/div><\/div><a class=\"w-btn us-btn-style_3 usg_btn_1 buttonabsoluterightbottom icon_atright\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/u-pad\/\"><span class=\"w-btn-label\">Plus d&rsquo;info<\/span><i class=\"fas fa-chevron-right\"><\/i><\/a><div class=\"w-vwrapper usg_vwrapper_2 newwrapper align_none valign_top\"><div class=\"w-image usg_image_1 newgrid\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png\" class=\"attachment-us_70_70 size-us_70_70\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-70x70.png 70w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-300x300.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-1024x1024.png 1024w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW-150x150.png 150w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Buzon-Macaron-NEW.png 1080w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/div><\/div><time class=\"w-post-elm post_date usg_post_date_1 postdate entry-date published\" datetime=\"2022-07-05T15:50:11+02:00\">2022-07-05<\/time><\/div><div class=\"w-html usg_html_1\"><script>\n\t\nvar divArray = \tdocument.getElementsByClassName(\"newwrapper\");\n\nfor (i = 0; i < divArray.length; i++) {\nconst uitleesdata = document.getElementsByClassName(\"postdate\")[i].innerHTML;\nconst then = new Date(uitleesdata);\nconst now = new Date();\n\nconst msBetweenDates = Math.abs(then.getTime() - now.getTime());\n\nconst daysBetweenDates = msBetweenDates \/ (24 * 60 * 60 * 1000);\n\nif (daysBetweenDates < 14) {\n} else {\n  divArray[i].style.display = \"none\";\n}\t\n\t}\n\n<\/script><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n<\/div>\t<div class=\"w-grid-preloader\">\r\n\t\t<div class=\"g-preloader type_1\">\r\n\t\t\t<div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:1,&quot;pagination&quot;:&quot;ajax&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;3&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;ignore_items_size&quot;:0,&quot;items_layout&quot;:&quot;581&quot;,&quot;items_offset&quot;:&quot;1&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22url%22%3A%22%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;post_type&quot;:[&quot;page&quot;],&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;accesories_category&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:&quot;terrasse-en-dalles-sur-lambourdes&quot;}],&quot;post_status&quot;:[&quot;publish&quot;,&quot;acf-disabled&quot;],&quot;posts_per_page&quot;:999},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:{&quot;menu_order&quot;:&quot;ASC&quot;},&quot;order&quot;:&quot;ASC&quot;},&quot;type&quot;:&quot;grid&quot;,&quot;us_grid_post_type&quot;:&quot;page&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_query_string&quot;:null,&quot;us_grid_index&quot;:1,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;fr&quot;}}'><\/div>\r\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"l-section wpb_row us_custom_6a388dfb bluerowbackground height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_boxes reversed stacking_default\"><div class=\"vc_col-sm-7 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_6df4bc3a has_text_color\"><div class=\"wpb_wrapper\"><h2>Question technique ?<br \/>\nUn nouveau projet ?<br \/>\nContactez l&rsquo;un de nos experts.<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" href=\"mailto:info@buzon-world.com\"><span class=\"w-btn-label\">info@buzon-world.com<\/span><\/a><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" href=\"tel:003242483983\"><span class=\"w-btn-label\">00 32 (0) 4 248 39 83<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image cupabsolute align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"577\" height=\"527\" src=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Rectangle-120.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Rectangle-120.png 577w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Rectangle-120-300x274.png 300w, https:\/\/www.buzon-world.com\/wp-content\/uploads\/2022\/07\/Rectangle-120-70x64.png 70w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_raw_html]JTVCd3BzZW9fYnJlYWRjcnVtYiU1RCUwQQ==[\/vc_raw_html]2022-07-05Matelas pour plots U-PAD-3MM (12 1837) \/ U-PAD-6MM (12 2027) \/ U-PAD-10MM (12 1835) Le matelas (U-PAD) est constitu\u00e9 de caoutchouc recycl\u00e9 imputrescible et se place sous le plot. Disponibles en 3 \u00e9paisseurs : Avantages et utilisations Permet de poser le plot sur un sol dont la finition est irr\u00e9guli\u00e8re, comme un b\u00e9ton grossier. Prot\u00e8ge...","protected":false},"author":6,"featured_media":42617,"parent":10245,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"accesories_category":[],"sizes":[],"plot_serie":[],"accesories_category_type":[],"accessories_categories_subtype":[],"accessories_categories_applica":[],"class_list":["post-42626","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum joist E-BRS | Buzon World support system<\/title>\n<meta name=\"description\" content=\"Slides into the joist and is used to hold the peripheral paversin position.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum joist E-BRS | Buzon World support system\" \/>\n<meta property=\"og:description\" content=\"Slides into the joist and is used to hold the peripheral paversin position.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/\" \/>\n<meta property=\"og:site_name\" content=\"Buzon\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T08:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/\",\"url\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/\",\"name\":\"Aluminum joist E-BRS | Buzon World support system\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.buzon-world.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/E-BRS-STOP-ROUND-PACKSHOT-v02.png\",\"datePublished\":\"2025-01-21T10:12:30+00:00\",\"dateModified\":\"2026-05-05T08:49:47+00:00\",\"description\":\"Slides into the joist and is used to hold the peripheral paversin position.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.buzon-world.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/E-BRS-STOP-ROUND-PACKSHOT-v02.png\",\"contentUrl\":\"https:\\\/\\\/www.buzon-world.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/E-BRS-STOP-ROUND-PACKSHOT-v02.png\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/e-brs-stop-round\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accessoires\",\"item\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accessoires U-BRS System\",\"item\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/produits\\\/accessoires\\\/accessoires-u-brs-system\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"E-BRS-STOP-ROUND\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/\",\"name\":\"Buzon\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.buzon-world.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aluminum joist E-BRS | Buzon World support system","description":"Slides into the joist and is used to hold the peripheral paversin position.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/","og_locale":"fr_FR","og_type":"article","og_title":"Aluminum joist E-BRS | Buzon World support system","og_description":"Slides into the joist and is used to hold the peripheral paversin position.","og_url":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/","og_site_name":"Buzon","article_modified_time":"2026-05-05T08:49:47+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/","url":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/","name":"Aluminum joist E-BRS | Buzon World support system","isPartOf":{"@id":"https:\/\/www.buzon-world.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/#primaryimage"},"image":{"@id":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/#primaryimage"},"thumbnailUrl":"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png","datePublished":"2025-01-21T10:12:30+00:00","dateModified":"2026-05-05T08:49:47+00:00","description":"Slides into the joist and is used to hold the peripheral paversin position.","breadcrumb":{"@id":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/#primaryimage","url":"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png","contentUrl":"https:\/\/www.buzon-world.com\/wp-content\/uploads\/2024\/12\/E-BRS-STOP-ROUND-PACKSHOT-v02.png","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/e-brs-stop-round\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buzon-world.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.buzon-world.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Accessoires","item":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/"},{"@type":"ListItem","position":4,"name":"Accessoires U-BRS System","item":"https:\/\/www.buzon-world.com\/fr\/produits\/accessoires\/accessoires-u-brs-system\/"},{"@type":"ListItem","position":5,"name":"E-BRS-STOP-ROUND"}]},{"@type":"WebSite","@id":"https:\/\/www.buzon-world.com\/fr\/#website","url":"https:\/\/www.buzon-world.com\/fr\/","name":"Buzon","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buzon-world.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/pages\/42626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/comments?post=42626"}],"version-history":[{"count":8,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/pages\/42626\/revisions"}],"predecessor-version":[{"id":58887,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/pages\/42626\/revisions\/58887"}],"up":[{"embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/pages\/10245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/media\/42617"}],"wp:attachment":[{"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/media?parent=42626"}],"wp:term":[{"taxonomy":"accesories_category","embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/accesories_category?post=42626"},{"taxonomy":"sizes","embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/sizes?post=42626"},{"taxonomy":"plot_serie","embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/plot_serie?post=42626"},{"taxonomy":"accesories_category_type","embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/accesories_category_type?post=42626"},{"taxonomy":"accessories_categories_subtype","embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/accessories_categories_subtype?post=42626"},{"taxonomy":"accessories_categories_applica","embeddable":true,"href":"https:\/\/www.buzon-world.com\/fr\/wp-json\/wp\/v2\/accessories_categories_applica?post=42626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}